{"id":22594,"date":"2020-10-29T09:00:30","date_gmt":"2020-10-29T08:00:30","guid":{"rendered":"https:\/\/www.mtp.es\/?p=22594"},"modified":"2026-08-28T10:29:29","modified_gmt":"2026-08-28T08:29:29","slug":"soy-el-ceo-y-necesito-tu-ayuda","status":"publish","type":"post","link":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/","title":{"rendered":"&#8220;Soy el CEO y necesito tu ayuda&#8221;"},"content":{"rendered":"\n<p><em>\u201cSoy el CEO y necesito tu ayuda\u201d<\/em>. Con una frase similar a \u00e9sta empiezan todas las conversaciones de la \u201c<strong><em>Estafa del CEO<\/em><\/strong>\u201d, que es un tipo de enga\u00f1o que est\u00e1 teniendo mucho auge en los \u00faltimos tiempos. En muchas ocasiones ha abierto titulares de informativos y peri\u00f3dicos; de hecho, se estima que este fraude ha superado los <strong>23.000 millones de euros<\/strong> <strong>estafados<\/strong> en todo el mundo, seg\u00fan datos del FBI.<\/p>\n\n\n\n<p>La estafa va dirigida a empleados de compa\u00f1\u00edas que tienen acceso a <strong>operaciones financieras<\/strong>. En la misma, bajo diferentes t\u00e9cnicas y medios se intenta hacerse pasar por el CEO o un puesto de direcci\u00f3n similar para que el trabajador realice operaciones urgentes con mucha confidencialidad y urgencia.<\/p>\n\n\n\n<p>La mayor\u00eda de las veces, las empresas objetivo son medianas o grandes, ya que en muchas ocasiones tienen una comunicaci\u00f3n mucho menos cercana o fluida que una peque\u00f1a y la sospecha de enga\u00f1o de las victimas es menor.<\/p>\n\n\n\n<p>Hay que tener en cuenta que lo m\u00e1s importante del ataque es que juega con la buena voluntad de las personas. \u00bfO acaso alguien dudar\u00eda en atender una solicitud como la que dicta el t\u00edtulo de este post \u201c<strong><em>Soy el CEO y necesito tu ayuda<\/em><\/strong>\u201d? Seguro que todos nosotros pondr\u00edamos todo lo que estuviera a nuestro alcance por ser r\u00e1pidos y eficaces en la gesti\u00f3n que se nos ha encomendado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Timo cambiante<\/strong><\/h3>\n\n\n\n<p>Este timo es conocido por lo cambiante y personalizado que es. Los delincuentes suelen aprovechar alguna <strong>vulnerabilidad que afecte a esas personas<\/strong> -como el robo de credenciales- para acceder a sus equipos y\/o entornos de trabajo para tener acceso a toda la informaci\u00f3n posible de la organizaci\u00f3n, aunque en ocasiones basta simplemente con la informaci\u00f3n p\u00fablica de los empleados o de la firma para elaborar la estrategia de ataque a seguir.<\/p>\n\n\n\n<p>Como coment\u00e1bamos, los estafadores usan diferentes <a href=\"https:\/\/mtp.global\/es\/blog\/ciberseguridad-mtp\/la-importancia-de-estar-concienciado-sobre-ciberseguridad\/\"><strong>t\u00e9cnicas de ingenier\u00eda social<\/strong><\/a> para el enga\u00f1o, desde el env\u00edo\/recepci\u00f3n de correos fraudulentos <strong>(<em>phishing<\/em>)<\/strong>, hasta llamadas telef\u00f3nicas <strong>(<em>vhishing<\/em>)<\/strong> e incluso en algunas ocasiones por mensajer\u00eda instant\u00e1nea como <em>WhatsApp<\/em> o similares.<\/p>\n\n\n\n<p>Para saber que t\u00e9cnica utilizar y que sea lo m\u00e1s efectiva posible, los criminales suelen realizar un estudio previo de cu\u00e1les son las comunicaciones m\u00e1s utilizados en la compa\u00f1\u00eda y realizan cada una de las t\u00e9cnicas o una combinaci\u00f3n de \u00e9stas para que sean lo m\u00e1s similares a la realidad, y as\u00ed no ser descubiertos.<\/p>\n\n\n\n<p>En los \u00faltimos a\u00f1os son much\u00edsimas las empresas que han sido v\u00edctimas de este ataque, si bien es cierto que muy pocas de ellas dan a conocer las consecuencias sufridas por miedo sobre todo a la correspondiente perdida de reputaci\u00f3n. Pero esta estafa est\u00e9 d\u00eda a d\u00eda haci\u00e9ndose efectiva en todo tipo de compa\u00f1\u00edas, llegando en muchas ocasiones a generar grandes p\u00e9rdidas.<\/p>\n\n\n\n<p>Por ello, es fundamental tener en las empresas una buena pol\u00edtica de <a href=\"https:\/\/mtp.global\/es\/blog\/ciberseguridad-mtp\/la-ciberseguridad-tarea-de-todos\/\"><strong>concienciaci\u00f3n de seguridad de las personas<\/strong><\/a> que la componen para que estos sean el principal escudo contra este tipo de ataques.<\/p>\n\n\n\n<p>Hacemos a continuaci\u00f3n algunas <strong>recomendaciones<\/strong> espec\u00edficas para que las posiciones que puedan realizar operaciones financieras no sean v\u00edctima de este fraude:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se debe de <strong>verificar<\/strong> siempre la direcci\u00f3n del remitente en un correo o el tel\u00e9fono de la persona que nos llama o escribe.<\/li>\n<li><strong>Sospechar<\/strong> por defecto, sobre todo de alguna operativa que no estemos acostumbrados a hacer o de cualquier compa\u00f1ero con la que no estamos acostumbrados a trabajar.<\/li>\n<li><strong>Comprobar <\/strong>con otras personas (compa\u00f1eros o responsables) los datos de cualquier operaci\u00f3n financiera antes de su ejecuci\u00f3n.<\/li>\n<li>Tener especial <strong>cuidado con amenazas o recompensas<\/strong> que nos puedan ofrecer y siempre desconfiar de las mismas.<\/li>\n<li><strong>Definir procedimientos de seguridad<\/strong> para la realizaci\u00f3n de cualquier pago e incluso implementar en los mismos sistemas de doble autorizaci\u00f3n de todas las operaciones.<\/li>\n<\/ul>\n\n\n\n<p>Por \u00faltimo, queremos recordar que a la m\u00ednima sospecha de que alguna acci\u00f3n similar a la que hemos comentado nos ocurra, no se debe ejecutar la operaci\u00f3n financiera sin verificar la legitimad de la misma por alg\u00fan medio, visto que es un delito que lleva mucho tiempo entre nosotros. Es mejor en estos casos pecar de prudencia.<\/p>\n\n\n\n<p><strong>Fernando Saavedra<\/strong><\/p>\n\n\n\n<p>Manager de Ciberseguridad MTP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Manager de Ciberseguridad de MTP, Fernando Saavedra, nos explica en este post en qu\u00e9 consiste la conocida como \u201cEstafa del CEO\u201d, que tiene como objetivo de sus ataques a empleados de compa\u00f1\u00edas con acceso a operaciones financieras. Tambi\u00e9n nos recuerda la importancia de la concienciaci\u00f3n de todos los empleados para asegurar la ciberseguridad.<\/p>\n","protected":false},"author":9,"featured_media":22592,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[204],"tags":[145],"class_list":["post-22594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","tag-ciberseguridad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Soy el CEO y necesito tu ayuda&quot;<\/title>\n<meta name=\"description\" content=\"El Manager de Ciberseguridad de MTP, Fernando Saavedra, nos explica en este post en qu\u00e9 consiste la conocida como \u201cEstafa del CEO\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Soy el CEO y necesito tu ayuda&quot;\" \/>\n<meta property=\"og:description\" content=\"El Manager de Ciberseguridad de MTP, Fernando Saavedra, nos explica en este post en qu\u00e9 consiste la conocida como \u201cEstafa del CEO\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/\" \/>\n<meta property=\"og:site_name\" content=\"MTP Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-29T08:00:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T08:29:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mtp.global\/es\/wp-content\/uploads\/2020\/10\/CS_MTP_blog-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MTP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MTP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Soy el CEO y necesito tu ayuda\"","description":"El Manager de Ciberseguridad de MTP, Fernando Saavedra, nos explica en este post en qu\u00e9 consiste la conocida como \u201cEstafa del CEO\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/","og_locale":"es_ES","og_type":"article","og_title":"\"Soy el CEO y necesito tu ayuda\"","og_description":"El Manager de Ciberseguridad de MTP, Fernando Saavedra, nos explica en este post en qu\u00e9 consiste la conocida como \u201cEstafa del CEO\u201d.","og_url":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/","og_site_name":"MTP Espa\u00f1a","article_published_time":"2020-10-29T08:00:30+00:00","article_modified_time":"2026-08-28T08:29:29+00:00","og_image":[{"width":1920,"height":1100,"url":"https:\/\/mtp.global\/es\/wp-content\/uploads\/2020\/10\/CS_MTP_blog-1.jpg","type":"image\/jpeg"}],"author":"MTP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MTP","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/#article","isPartOf":{"@id":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/"},"author":{"name":"MTP","@id":"https:\/\/mtp.global\/es\/#\/schema\/person\/1186350db6f59e8360dd481150654813"},"headline":"&#8220;Soy el CEO y necesito tu ayuda&#8221;","datePublished":"2020-10-29T08:00:30+00:00","dateModified":"2026-08-28T08:29:29+00:00","mainEntityOfPage":{"@id":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/"},"wordCount":746,"publisher":{"@id":"https:\/\/mtp.global\/es\/#organization"},"image":{"@id":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/#primaryimage"},"thumbnailUrl":"https:\/\/mtp.global\/es\/wp-content\/uploads\/2020\/10\/CS_MTP_blog-1.jpg","keywords":["ciberseguridad"],"articleSection":["Archivo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/","url":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/","name":"\"Soy el CEO y necesito tu ayuda\"","isPartOf":{"@id":"https:\/\/mtp.global\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/#primaryimage"},"image":{"@id":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/#primaryimage"},"thumbnailUrl":"https:\/\/mtp.global\/es\/wp-content\/uploads\/2020\/10\/CS_MTP_blog-1.jpg","datePublished":"2020-10-29T08:00:30+00:00","dateModified":"2026-08-28T08:29:29+00:00","description":"El Manager de Ciberseguridad de MTP, Fernando Saavedra, nos explica en este post en qu\u00e9 consiste la conocida como \u201cEstafa del CEO\u201d.","breadcrumb":{"@id":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/#primaryimage","url":"https:\/\/mtp.global\/es\/wp-content\/uploads\/2020\/10\/CS_MTP_blog-1.jpg","contentUrl":"https:\/\/mtp.global\/es\/wp-content\/uploads\/2020\/10\/CS_MTP_blog-1.jpg","width":1920,"height":1100,"caption":"Ciberseguridad MTP"},{"@type":"BreadcrumbList","@id":"https:\/\/mtp.global\/es\/blog\/archivo\/soy-el-ceo-y-necesito-tu-ayuda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mtp.global\/es\/home\/"},{"@type":"ListItem","position":2,"name":"&#8220;Soy el CEO y necesito tu ayuda&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/mtp.global\/es\/#website","url":"https:\/\/mtp.global\/es\/","name":"MTP Global","description":"","publisher":{"@id":"https:\/\/mtp.global\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mtp.global\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mtp.global\/es\/#organization","name":"MTP Global","url":"https:\/\/mtp.global\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mtp.global\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mtp.global\/es\/wp-content\/uploads\/2024\/07\/MTP-global.png","contentUrl":"https:\/\/mtp.global\/es\/wp-content\/uploads\/2024\/07\/MTP-global.png","width":1200,"height":400,"caption":"MTP Global"},"image":{"@id":"https:\/\/mtp.global\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mtp.global\/es\/#\/schema\/person\/1186350db6f59e8360dd481150654813","name":"MTP","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9f80fcebb065607a1066a38846083841707346cf76ca0c1df24aea7a0c5d4047?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f80fcebb065607a1066a38846083841707346cf76ca0c1df24aea7a0c5d4047?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f80fcebb065607a1066a38846083841707346cf76ca0c1df24aea7a0c5d4047?s=96&d=mm&r=g","caption":"MTP"},"url":"https:\/\/mtp.global\/es\/blog\/author\/marketing\/"}]}},"fimg_url":"https:\/\/mtp.global\/es\/wp-content\/uploads\/2020\/10\/CS_MTP_blog-1.jpg","_links":{"self":[{"href":"https:\/\/mtp.global\/es\/wp-json\/wp\/v2\/posts\/22594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mtp.global\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mtp.global\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mtp.global\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/mtp.global\/es\/wp-json\/wp\/v2\/comments?post=22594"}],"version-history":[{"count":0,"href":"https:\/\/mtp.global\/es\/wp-json\/wp\/v2\/posts\/22594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mtp.global\/es\/wp-json\/wp\/v2\/media\/22592"}],"wp:attachment":[{"href":"https:\/\/mtp.global\/es\/wp-json\/wp\/v2\/media?parent=22594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mtp.global\/es\/wp-json\/wp\/v2\/categories?post=22594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mtp.global\/es\/wp-json\/wp\/v2\/tags?post=22594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}